{"id":5212,"count":15,"description":"Orgulhamo-nos da nossa qualidade sem compromissos. Todos os nossos produtos refor\u00e7ados, laptops, notebooks e touchpads s\u00e3o concebidos para serem resistentes e suportarem uma utiliza\u00e7\u00e3o intensiva em ambientes extremos e movimentados. \n\nOs tablets e laptops robustos oferecem mobilidade e prote\u00e7\u00e3o que os computadores normais n\u00e3o conseguem proporcionar. S\u00e3o concebidos para resistir a quedas e impactos di\u00e1rios em ambientes de trabalho adversos e exigentes, bem como para suportar chuva, poeira, choques e calor, mantendo-o sempre ligado e seguro. ","link":"https:\/\/micronordic.com\/pt-pt\/category\/all-rugged-laptops\/","name":"Todos os Rugged Laptops","slug":"all-rugged-laptops","taxonomy":"product_cat","parent":0,"meta":[],"menu_order":1,"acf":[],"_links":{"self":[{"href":"https:\/\/micronordic.com\/pt-pt\/wp-json\/wp\/v2\/product_cat\/5212","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/micronordic.com\/pt-pt\/wp-json\/wp\/v2\/product_cat"}],"about":[{"href":"https:\/\/micronordic.com\/pt-pt\/wp-json\/wp\/v2\/taxonomies\/product_cat"}],"wp:post_type":[{"href":"https:\/\/micronordic.com\/pt-pt\/wp-json\/wp\/v2\/product?product_cat=5212"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}